{"id":460,"date":"2017-07-19T09:28:56","date_gmt":"2017-07-19T09:28:56","guid":{"rendered":"http:\/\/www.nicdarkthemes.com\/themes\/hotel\/wp\/demo\/?page_id=460"},"modified":"2024-08-12T13:15:33","modified_gmt":"2024-08-12T18:15:33","slug":"contact","status":"publish","type":"page","link":"https:\/\/haciendadelmar.net\/es\/contact\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_custom_1476343737841\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Lo invitamos a experimentar un lugar de incomparable belleza, relajaci\u00f3n y aventura. Comida org\u00e1nica de cosecha propia, mariscos frescos, cordial hospitalidad de La Isla de Las Perlas, arrecifes naturales para explorar en aguas cristalinas y 14,400 acres de selva virgen virgen. Todo esto es solo un vistazo de lo que te espera en Hacienda Del Mar.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Las habitaciones espaciosas y \u00fanicas de Hacienda del Mar combinan el encanto isle\u00f1o y el confort moderno, todo a solo unos pasos de la playa. Nuestro resort ecol\u00f3gico ofrece 5 tipos de caba\u00f1as frente al mar o con vista a la playa, a saber, caba\u00f1as de la suite Toucan, caba\u00f1as de la suite junior, caba\u00f1as de la suite VIP, suites HDM y suite Admiral. Cada caba\u00f1a ofrece una variedad de comodidades para que la estad\u00eda de nuestros hu\u00e9spedes sea lo m\u00e1s despreocupada y c\u00f3moda posible, como camas dobles y extra grandes, aire acondicionado, iluminaci\u00f3n y ventiladores de techo, grandes ba\u00f1os privados con azulejos con duchas de agua caliente y el agua m\u00e1s fresca. Adem\u00e1s, las caba\u00f1as VIP, Jr Suites, HDM Suites y Admiral Suite tienen un mini refrigerador con refrigerios y facilidades para preparar caf\u00e9 y t\u00e9.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1492593618245\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div> <h3 style=\"color:;padding:px;text-align:;font-size:25px;line-height:25px;letter-spacing: px;font-weight:normal\" class=\"nd_options_first_font\">Escr\u00edbenos<\/h3> <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <!--start form-->\n    <div id=\"nd_options_shortcode_cf7_1199\" class=\"nd_options_section\">\n      \n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1199-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/460#wpcf7-f1199-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/460#wpcf7-f1199-o1\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1199\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1199-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-135\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-135\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Message\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" autocomplete=\"name\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Message\" \/><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n \n      <\/div>  \n\n    <\/div>\n    <!--end form-->\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div> <h3 style=\"color:;padding:px;text-align:;font-size:25px;line-height:25px;letter-spacing: px;font-weight:normal\" class=\"nd_options_first_font\">Preguntas frecuentes<\/h3> <div style=\"background-color:;height: 30px\" class=\"nicdark_section\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Comun\u00edquese con nosotros si tiene preguntas o inquietudes adicionales.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div style=\"background-color:;height: 25px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_697 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_697 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfC\u00f3mo llego a Hacienda del Mar en Panam\u00e1?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_697 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Todo lo que tiene que hacer es planificar su vuelo internacional al Aeropuerto Internacional de Tocumen de Panam\u00e1 y trasladarse (en taxi, uber o conductor privado) al Aeropuerto Marco A. Gelabert en Albrook, Ciudad de Panam\u00e1, que est\u00e1 aproximadamente a 20 minutos del Aeropuerto de Tocumen. Una vez en la terminal, debe registrarse en su vuelo a la isla de San Jos\u00e9. Llegar\u00e1 25 minutos m\u00e1s tarde y lo estaremos esperando para acompa\u00f1arlo al resort. Lo llevaremos 20 minutos a trav\u00e9s de la selva virgen y los r\u00edos mientras observa la vida silvestre como iguanas, venados, jabal\u00edes y aves hasta que llegue a la Hacienda Del Mar. Opcionalmente, puede viajar en bote (aprox. 2 1\/2 horas). Cons\u00faltenos para m\u00e1s detalles.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 18px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_790 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_790 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfHacienda ayuda con traslados al aeropuerto y transporte a\u00e9reo a Hacienda del Mar?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_790 nd_options_section nd_options_box_sizing_border_box\">\n        <p>S\u00ed, con gusto nos ocupamos de todas las reservas a\u00e9reas desde y hacia el aeropuerto de Albrook hasta la isla de San Jos\u00e9. Nosotros, si lo desea nuestro hu\u00e9sped, podemos manejar los traslados locales, as\u00ed como la coordinaci\u00f3n de tours de la Ciudad de Panam\u00e1, el Canal de Panam\u00e1, y las reservas de hotel de la Ciudad de Panam\u00e1 (si es necesario), etc.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 18px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_907 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_907 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfA qu\u00e9 hora salen los vuelos a Hacienda Del Mar (Isla San Jos\u00e9) desde el Aeropuerto de Albrook?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_907 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Los vuelos son los siguientes: Lunes a s\u00e1bado Vuelos: Salida de Albrook: 8:30 am. Llegada a San Jos\u00e9: 8:50 am. Salida de San Jos\u00e9 9:00 am: Llegada a Albrook: 9:25 am. Vuelos Domingos: Salida de Albrook: 3:00 pm. Llegada a San Jos\u00e9: 3:20 pm. Salida de San Jos\u00e9 3:30 pm: Llegada a Albrook: 3:55 pm.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 18px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_724 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_724 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfCu\u00e1l es el costo del pasaje a\u00e9reo de ida y vuelta a la isla de San Jos\u00e9?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_724 nd_options_section nd_options_box_sizing_border_box\">\n        <p>The cost of the flight is $ 250.00 per person round trip including all taxes. Departing from Marcos A. Gelabert Airport. Flights: Tuesday and Friday mornings. Sunday afternoons. (Subject to availability). For flights on other dates and times, please quote charter flights.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 18px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_541 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_541 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfCu\u00e1l es la mejor \u00e9poca del a\u00f1o para ir?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_541 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Todo el a\u00f1o.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_966 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_966 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfQu\u00e9 deber\u00eda llevar?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_966 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Bronceador, anteojos de sol, sombrero y alg\u00fan repelente de insectos para usar en \u00e1reas remotas de la isla.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_340 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_340 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfQu\u00e9 tipo de ropa debo traer?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_340 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Jeans, camisas de manga corta y larga, shorts y ba\u00f1adores, zapatillas deportivas, sandalias. Ropa c\u00f3moda.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_611 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_611 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfCu\u00e1les son los horarios de entrada y salida?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_611 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Por la ma\u00f1ana a la hora de llegada y por la tarde a la hora de salida. Usted se beneficia al poder registrarse antes del mediod\u00eda y una salida tard\u00eda autom\u00e1tica el d\u00eda de su salida.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <div class=\"nd_options_section nd_options_toogles_contact_2\">\n\n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        <p class=\"nd_options_toogle_title nd_options_first_font nd_options_font_size_17 nd_options_position_relative nd_options_padding_right_20 nd_options_padding_top_5 nd_options_padding_left_45 nd_options_padding_bottom_5\">\n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_open_302 nd_options_width_25 nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-add-white.png\">\n          <\/span> \n          <span style=\"background-color:#78635a\" class=\"nd_options_cursor_pointer nd_options_text_align_center nd_options_toogle_title_close_302 nd_options_width_25 nd_options_display_none nd_options_height_25  nd_options_position_absolute nd_options_top_0 nd_options_left_0\">\n            <img decoding=\"async\" alt=\"\" class=\"nd_options_margin_top_6\" width=\"12\" src=\"https:\/\/haciendadelmar.net\/wp-content\/plugins\/nd-shortcodes\/shortcodes\/custom\/toogle\/icon-less-white.png\">\n          <\/span>\n          \u00bfQu\u00e9 equipo debo llevar para pescar?\n        <\/p>\n      <\/div>\n      \n      <div class=\"nd_options_display_none nd_options_padding_20 nd_options_padding_left_45 nd_options_toogle_content_302 nd_options_section nd_options_box_sizing_border_box\">\n        <p>Hacienda Del Mar tiene todo lo necesario para la pesca. Mantenemos el equipo adecuado. Sin embargo, se recomienda que los pescadores, si lo desean, traigan su ca\u00f1a y carretes favoritos.<\/p>\n      <\/div>\n\n    <\/div>\n\n   <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d25807.82288700167!2d-79.10552536446583!3d8.225933793636415!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x8e52d94bffffffff%3A0xd27d9ef486e48db5!2sHacienda%20del%20Mar!5e0!3m2!1ses!2spa!4v1617740813970!5m2!1ses!2spa\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1617741115173 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:;height: 10px\" class=\"nicdark_section\"><\/div> <h3 style=\"color:#ffffff;padding:px;text-align:center;font-size:13px;line-height:13px;letter-spacing: 2px;font-weight:lighter\" class=\"nd_options_second_font\">PONGASE EN CONTACTO<\/h3>  <h1 style=\"color:#ffffff;padding:px;text-align:center;font-size:30px;line-height:35px;letter-spacing: px;font-weight:normal\" class=\"nd_options_first_font\">No dude en contactarnos para cualquier consulta o duda.<\/h1> <\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1505896552119 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"> <h3 style=\"color:#ffffff;padding:px;text-align:;font-size:20px;line-height:12px;letter-spacing: px;font-weight:bold\" class=\"nd_options_first_font\">Reservaciones<\/h3> <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:15px;line-height:15px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_25_responsive nd_options_second_font\">CONTACTO INTERNACIONAL<\/p> <div style=\"background-color:;height: 5px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:10px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_25_responsive nd_options_second_font\">+1 (786) 395-7491<\/p> <div style=\"background-color:;height: 5px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:10px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_25_responsive nd_options_second_font\">reservations@haciendadelmar.net<\/p> <div style=\"background-color:;height: 25px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:15px;line-height:15px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_25_responsive nd_options_second_font\">CONTACTO PANAM\u00c1<\/p> <div style=\"background-color:;height: 5px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:10px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_25_responsive nd_options_second_font\">+ 507 269-6634 \/ +507 6678-5965<\/p> <div style=\"background-color:;height: 5px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:10px;letter-spacing: 1px;font-weight:\" class=\"nd_options_margin_bottom_50_responsive nd_options_second_font\">info@haciendadelmar.net<\/p> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"> <h3 style=\"color:#ffffff;padding:px;text-align:;font-size:20px;line-height:20px;letter-spacing: px;font-weight:bold\" class=\"nd_options_first_font\">Conecta con nosotros<\/h3> <div style=\"background-color:;height: 10px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:12px;letter-spacing: px;font-weight:\" class=\"nd_options_second_font\">NUESTRAS REDES SOCIALES<\/p> <div style=\"background-color:;height: 30px\" class=\"nicdark_section\"><\/div>\n\t\n\t<a style=\"margin:0px 20px 0px 0px;border: px solid;border-radius:px;background-color:;padding:\" rel=\"\" href=\"https:\/\/www.facebook.com\/HaciendaDelMarPanama\" class=\"nicdark_display_inline_block nd_options_float_left\"><img decoding=\"async\" class=\"nd_options_float_left\" alt=\"\" width=\"20\" src=\"https:\/\/haciendadelmar.net\/wp-content\/uploads\/2017\/07\/icon-6.png\"><\/a>\n\t\n\n\t\n\t<a style=\"margin:0px 20px 0px 0px;border: px solid;border-radius:px;background-color:;padding:\" rel=\"\" href=\"https:\/\/www.instagram.com\/haciendadelmar\/\" class=\"nicdark_display_inline_block nd_options_float_left\"><img decoding=\"async\" class=\"nd_options_float_left\" alt=\"\" width=\"20\" src=\"https:\/\/haciendadelmar.net\/wp-content\/uploads\/2017\/07\/icon-4.png\"><\/a>\n\t\n\n\t\n\t<a style=\"margin:0px 20px 0px 0px;border: px solid;border-radius:px;background-color:;padding:\" rel=\"\" href=\"https:\/\/www.pinterest.es\/haciendadelmarpanama\" class=\"nicdark_display_inline_block nd_options_float_left\"><img decoding=\"async\" class=\"nd_options_float_left\" alt=\"\" width=\"20\" src=\"https:\/\/haciendadelmar.net\/wp-content\/uploads\/2017\/07\/icon-7.png\"><\/a>\n\t\n\n\t\n\t<a style=\"margin:0px 20px 0px 0px;border: px solid;border-radius:px;background-color:;padding:\" rel=\"\" href=\"https:\/\/www.tiktok.com\/@haciendadelmar\" class=\"nicdark_display_inline_block nd_options_float_left\"><img decoding=\"async\" class=\"nd_options_float_left\" alt=\"\" width=\"20\" src=\"https:\/\/haciendadelmar.net\/wp-content\/uploads\/2021\/05\/tiktok-01-01.png\"><\/a>\n\t\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"> <h3 style=\"color:#ffffff;padding:px;text-align:;font-size:20px;line-height:20px;letter-spacing: px;font-weight:bold\" class=\"nd_options_margin_top_50_responsive nd_options_first_font\">Bolet\u00edn informativo<\/h3> <div style=\"background-color:;height: 10px\" class=\"nicdark_section\"><\/div> <p style=\"color:#ffffff;padding:px;text-align:;font-size:12px;line-height:12px;letter-spacing: px;font-weight:\" class=\"nd_options_second_font\">REG\u00cdSTRESE PARA OFERTAS ESPECIALES<\/p> <div style=\"background-color:;height: 20px\" class=\"nicdark_section\"><\/div>\n\n    <!--start form-->\n    <div id=\"nd_options_shortcode_cf7_253\" class=\"nd_options_section\">\n      \n      <div class=\"nd_options_section nd_options_box_sizing_border_box\">\n        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f253-o2\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/460#wpcf7-f253-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/460#wpcf7-f253-o2\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"253\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f253-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n\n<div class=\"nd_options_float_left nd_options_box_sizing_border_box nd_options_width_100_percentage_all_iphone_important nd_options_padding_0_right_important_all_iphone nd_options_padding_0_left_important_all_iphone\" style=\"padding: 0px 0px 0px 0px;width:60%\"><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><\/span><\/div><div class=\"nd_options_float_left nd_options_box_sizing_border_box nd_options_width_100_percentage_all_iphone_important nd_options_padding_0_right_important_all_iphone nd_options_padding_0_left_important_all_iphone\" style=\"padding: 0px 0px 0px 0px;width:40%\"><\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n \n      <\/div>  \n\n    <\/div>\n    <!--end form-->\n\n   <\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"We invite you to experience a place of unsurpassed beauty, relaxation and adventure. Organic homegrown food, fresh seafood, heartfelt Pearl Island hospitality, natural reefs to explore in crystal clear waters, and 14,400 acres of unspoiled virgin rainforest. All this is just a glimpse of what awaits you at Hacienda Del Mar. &nbsp; Hacienda del Mar's [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-460","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/pages\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":23,"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/pages\/460\/revisions"}],"predecessor-version":[{"id":2540,"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/pages\/460\/revisions\/2540"}],"wp:attachment":[{"href":"https:\/\/haciendadelmar.net\/es\/wp-json\/wp\/v2\/media?parent=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}